{"id":1872,"date":"2012-01-10T22:20:18","date_gmt":"2012-01-10T22:20:18","guid":{"rendered":"http:\/\/www.vesuvioweb.com\/it\/?p=1872"},"modified":"2012-02-11T10:05:43","modified_gmt":"2012-02-11T10:05:43","slug":"raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi","status":"publish","type":"post","link":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/","title":{"rendered":"Raimondo Martorana &#8211; Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi"},"content":{"rendered":"<p><span style=\"color: #888888;\">ORME DI SANTI NEL CONVENTO DELLA SS, ANNUNZIATA DI TORRE DEL GRECO: SAN LORENZO DA BRINDISI<\/span><\/p>\n<p>Nato a Brindisi nel 1559, trascorse un\u2019infanzia circondato dall\u2019affetto dei suoi, genitori che lo educarono nei santi principi cristiani. All\u2019epoca, la presenza dei Turchi sulle coste pugliesi costituiva un pericolo per tutti gli abitanti per cui la madre, rimasta vedova, si trasfer\u00ec a Venezia. Entrato nel Convento dei Cappuccini, pot\u00e8 completare la sua formazione spirituale ed intellettuale frequentando l\u2019Universit\u00e0 di Padova. La sua vasta erudizione unita alla straordinaria conoscenza delle lingue tra cui il greco e l\u2019ebraico, gli ottennero parecchi incarichi nell\u2019Ord\u00edne da parte del Papa Paolo V che lo invi\u00f2 quale ambasciatore di pace presso principi e \u00edmperatori.<\/p>\n<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Raimondo-Martorana-Il-Convento-della-SS-Annunziata-di-Torre-del-Greco-e-San-Lorenzo-da-Brindisi-vesuvioweb.pdf\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1874\" title=\"icona_annunz_interm\" src=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunz_interm.jpg\" alt=\"\" width=\"699\" height=\"417\" srcset=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunz_interm.jpg 699w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunz_interm-300x178.jpg 300w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #888888;\"><strong><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Raimondo-Martorana-Il-Convento-della-SS-Annunziata-di-Torre-del-Greco-e-San-Lorenzo-da-Brindisi-vesuvioweb.pdf\"><span style=\"color: #888888;\">Raimondo Martorana &#8211; Il Convento della SS Annunziata di Torre del Greco e San Lorenzo da Brindisi &#8211; vesuvioweb<\/span><\/a><\/strong><\/span><\/p>\n<p>Fu durante la sua missione in Spagna che sost\u00f2 nel Convento dei Cappuccini di Torre del Greco dal 3 al 10 Ottobre del 1618 celebrando in quei giorni all\u2019altare della SS. Annunziata e dimor\u00f2 in una delle celle del Convento stesso. Come ci informa Padre Loffredo, S. Lorenzo da Brindisi part\u00ec dal Convento dei Cappuccini di Nola e sostando in quel di Barra, cavalcando una notte intera, raggiunse Torre del Greco, pur essendo febbricitante, onde poter partire verso la Spagna. La partenza avvenne in segreto, di notte, cosicch\u00e9 salp\u00f2 dal porto di Torre del Greco con la tramontana delle prime ore della notte. Ma perch\u00e9 S. Lorenzo si recava in Spagna?<\/p>\n<p><a href=\"http:\/\/www.vesuvioweb.com\/new\/info@vesuvioweb.com%3C\/strong%3E\"><strong>info@vesuvioweb.com<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ORME DI SANTI NEL CONVENTO DELLA SS, ANNUNZIATA DI TORRE DEL GRECO: SAN LORENZO DA&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[9,232],"tags":[],"class_list":["post-1872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-00-in-rilievo","category-le-chiese"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb\" \/>\n<meta property=\"og:description\" content=\"ORME DI SANTI NEL CONVENTO DELLA SS, ANNUNZIATA DI TORRE DEL GRECO: SAN LORENZO DA&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/\" \/>\n<meta property=\"og:site_name\" content=\"Vesuvioweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-10T22:20:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-11T10:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vesuvioweb\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vesuvioweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/\"},\"author\":{\"name\":\"Vesuvioweb\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\"},\"headline\":\"Raimondo Martorana &#8211; Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi\",\"datePublished\":\"2012-01-10T22:20:18+00:00\",\"dateModified\":\"2012-02-11T10:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona_annunziata.jpg\",\"articleSection\":[\"00 In Rilievo\",\"Le chiese\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/\",\"name\":\"Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona_annunziata.jpg\",\"datePublished\":\"2012-01-10T22:20:18+00:00\",\"dateModified\":\"2012-02-11T10:05:43+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona_annunziata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona_annunziata.jpg\",\"width\":\"452\",\"height\":\"421\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"name\":\"Vesuvioweb\",\"description\":\"Magazine di Cultura Vesuviana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\",\"name\":\"Vesuvioweb\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"width\":1000,\"height\":216,\"caption\":\"Vesuvioweb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\",\"name\":\"Vesuvioweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"caption\":\"Vesuvioweb\"},\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/author\\\/vesuvioweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/","og_locale":"it_IT","og_type":"article","og_title":"Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb","og_description":"ORME DI SANTI NEL CONVENTO DELLA SS, ANNUNZIATA DI TORRE DEL GRECO: SAN LORENZO DA&hellip;","og_url":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/","og_site_name":"Vesuvioweb","article_published_time":"2012-01-10T22:20:18+00:00","article_modified_time":"2012-02-11T10:05:43+00:00","og_image":[{"width":452,"height":421,"url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg","type":"image\/jpeg"}],"author":"Vesuvioweb","twitter_misc":{"Scritto da":"Vesuvioweb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#article","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/"},"author":{"name":"Vesuvioweb","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64"},"headline":"Raimondo Martorana &#8211; Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi","datePublished":"2012-01-10T22:20:18+00:00","dateModified":"2012-02-11T10:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg","articleSection":["00 In Rilievo","Le chiese"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/","url":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/","name":"Raimondo Martorana - Il Convento della SS. Annunziata di Torre del Greco e San Lorenzo da Brindisi - Vesuvioweb","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#primaryimage"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg","datePublished":"2012-01-10T22:20:18+00:00","dateModified":"2012-02-11T10:05:43+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/raimondo-martorana-il-convento-della-ss-annunziata-di-torre-del-greco-e-san-lorenzo-da-brindisi\/#primaryimage","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona_annunziata.jpg","width":"452","height":"421"},{"@type":"WebSite","@id":"https:\/\/www.vesuvioweb.com\/it\/#website","url":"https:\/\/www.vesuvioweb.com\/it\/","name":"Vesuvioweb","description":"Magazine di Cultura Vesuviana","publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vesuvioweb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vesuvioweb.com\/it\/#organization","name":"Vesuvioweb","url":"https:\/\/www.vesuvioweb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","width":1000,"height":216,"caption":"Vesuvioweb"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64","name":"Vesuvioweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","caption":"Vesuvioweb"},"url":"https:\/\/www.vesuvioweb.com\/it\/author\/vesuvioweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/1872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/comments?post=1872"}],"version-history":[{"count":0,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/1872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media\/1875"}],"wp:attachment":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media?parent=1872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/categories?post=1872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/tags?post=1872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}