{"id":19625,"date":"2024-06-15T16:49:27","date_gmt":"2024-06-15T14:49:27","guid":{"rendered":"https:\/\/www.vesuvioweb.com\/it\/?p=19625"},"modified":"2024-06-15T16:49:27","modified_gmt":"2024-06-15T14:49:27","slug":"la-testimonianza-fotografica-della-terra-vesuviana","status":"publish","type":"post","link":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/","title":{"rendered":"La testimonianza fotografica della Terra Vesuviana"},"content":{"rendered":"<h2 style=\"text-align: center;\"><span style=\"color: #000080;\"><strong>La testimonianza fotografica della Terra Vesuviana<\/strong><\/span><\/h2>\n<p style=\"text-align: center;\">Di<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000080;\"><strong>Vittorio Pandolfi<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Quando il governo e il mondo accademico di un Paese non\u00a0rivolgono le attenzioni dovute alla catalogazione, alla tutela e\u00a0allo studio di manufatti e ambienti che sfuggono all\u2019interesse dominante, assai cli frequente la pietas di singoli individui o di associazioni private interviene a supplire in tali attivit\u00e0. Non mi riferisco solo a quanto in Italia nel corso del XX\u00a0secolo hanno fatto il Touring Club Italiano, Italia Nostra, il WWF, l\u2019Istituto dei Castelli, il FAI, l\u2019Adsi o, a partire dal\u00a0secolo precedente, mecenati e collezionisti, spesso mercanti\u00a0e antiquari. Non penso solo alle collezioni del Museo Stibbert o di Louis Carrand al Bargello, ma a quelle della collezione Salce di Treviso, che custodisce la pi\u00f9 imponente serie\u00a0di manifesti che esiste in Italia, o alle \u201cpovere\u201d carte della\u00a0Raccolta Achille Bertarelli di Milano (i biglietti del tram, i\u00a0menu, etc.) o alla Casa Museo di Antonino Uccello a Palazzolo Acreide o ai cataloghi fotogra\ufb01ci di territori indagati a tappeto (ad esempio la Fototeca Nolana di Leonardo Avella iniziata sul \ufb01nire degli anni cinquanta).\u00a0A quest\u2019ambito culturale appartengono le fotogra\ufb01e che Vittorio Pandol\ufb01 ha scattato sulle pendici del Vesuvio, a Napoli e in tutti i luoghi che ha visitato.<\/p>\n<p>Oggi la raccolta e la catalogazione del vastissimo materiale documentario costituito dalle foto scattate dai privati nel corso del Novecento dovrebbe essere compito del Ministero e degli altri enti regionali e comunali preposti all\u2019amministrazione dei Beni culturali perch\u00e9, in assenza di una documentazione uf\ufb01ciale e \u201cministeriale\u201d, molte raf\ufb01gurazioni\u00a0di opere o di ambienti perduti sono rintracciabili in questo materiale, spesso di non altissima qualit\u00e0 dal punto di vista &#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Vitttorio-Pandolfi-La-testimonianza-fotografica-della-Terra-Vesuviana-vesuvioweb-2024.pub_.pdf\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-19628 size-large\" src=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-1017x1024.jpg\" alt=\"\" width=\"960\" height=\"967\" srcset=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-1017x1024.jpg 1017w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-298x300.jpg 298w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-150x150.jpg 150w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-768x773.jpg 768w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-600x604.jpg 600w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-156x156.jpg 156w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1-1320x1328.jpg 1320w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona1-1.jpg 1405w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800000;\"><strong><a style=\"color: #800000;\" href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Vitttorio-Pandolfi-La-testimonianza-fotografica-della-Terra-Vesuviana-vesuvioweb-2024.pub_.pdf\" target=\"_blank\" rel=\"noopener\">Vitttorio Pandolfi &#8211; La testimonianza fotografica della Terra Vesuviana -vesuvioweb 2024.pub<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La testimonianza fotografica della Terra Vesuviana Di Vittorio Pandolfi &nbsp; &nbsp; Quando il governo e&hellip;<\/p>\n","protected":false},"author":2,"featured_media":19627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[9,587],"tags":[],"class_list":["post-19625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-00-in-rilievo","category-san-giorgio-a-cremano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La testimonianza fotografica della Terra Vesuviana - Vesuvioweb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La testimonianza fotografica della Terra Vesuviana - Vesuvioweb\" \/>\n<meta property=\"og:description\" content=\"La testimonianza fotografica della Terra Vesuviana Di Vittorio Pandolfi &nbsp; &nbsp; Quando il governo e&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/\" \/>\n<meta property=\"og:site_name\" content=\"Vesuvioweb\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-15T14:49:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"438\" \/>\n\t<meta property=\"og:image:height\" content=\"633\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vesuvioweb\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vesuvioweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/\"},\"author\":{\"name\":\"Vesuvioweb\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\"},\"headline\":\"La testimonianza fotografica della Terra Vesuviana\",\"datePublished\":\"2024-06-15T14:49:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/\"},\"wordCount\":307,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-20.jpg\",\"articleSection\":[\"00 In Rilievo\",\"San Giorgio a Cremano\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/\",\"name\":\"La testimonianza fotografica della Terra Vesuviana - Vesuvioweb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-20.jpg\",\"datePublished\":\"2024-06-15T14:49:27+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2024\\\/06\\\/la-testimonianza-fotografica-della-terra-vesuviana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-20.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-20.jpg\",\"width\":438,\"height\":633},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"name\":\"Vesuvioweb\",\"description\":\"Magazine di Cultura Vesuviana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\",\"name\":\"Vesuvioweb\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"width\":1000,\"height\":216,\"caption\":\"Vesuvioweb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\",\"name\":\"Vesuvioweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"caption\":\"Vesuvioweb\"},\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/author\\\/vesuvioweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La testimonianza fotografica della Terra Vesuviana - Vesuvioweb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/","og_locale":"it_IT","og_type":"article","og_title":"La testimonianza fotografica della Terra Vesuviana - Vesuvioweb","og_description":"La testimonianza fotografica della Terra Vesuviana Di Vittorio Pandolfi &nbsp; &nbsp; Quando il governo e&hellip;","og_url":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/","og_site_name":"Vesuvioweb","article_published_time":"2024-06-15T14:49:27+00:00","og_image":[{"width":438,"height":633,"url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg","type":"image\/jpeg"}],"author":"Vesuvioweb","twitter_misc":{"Scritto da":"Vesuvioweb","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#article","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/"},"author":{"name":"Vesuvioweb","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64"},"headline":"La testimonianza fotografica della Terra Vesuviana","datePublished":"2024-06-15T14:49:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/"},"wordCount":307,"commentCount":1,"publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg","articleSection":["00 In Rilievo","San Giorgio a Cremano"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/","url":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/","name":"La testimonianza fotografica della Terra Vesuviana - Vesuvioweb","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#primaryimage"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg","datePublished":"2024-06-15T14:49:27+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/2024\/06\/la-testimonianza-fotografica-della-terra-vesuviana\/#primaryimage","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-20.jpg","width":438,"height":633},{"@type":"WebSite","@id":"https:\/\/www.vesuvioweb.com\/it\/#website","url":"https:\/\/www.vesuvioweb.com\/it\/","name":"Vesuvioweb","description":"Magazine di Cultura Vesuviana","publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vesuvioweb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vesuvioweb.com\/it\/#organization","name":"Vesuvioweb","url":"https:\/\/www.vesuvioweb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","width":1000,"height":216,"caption":"Vesuvioweb"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64","name":"Vesuvioweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","caption":"Vesuvioweb"},"url":"https:\/\/www.vesuvioweb.com\/it\/author\/vesuvioweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/19625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/comments?post=19625"}],"version-history":[{"count":0,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/19625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media\/19627"}],"wp:attachment":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media?parent=19625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/categories?post=19625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/tags?post=19625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}