{"id":468,"date":"2012-01-06T18:24:56","date_gmt":"2012-01-06T18:24:56","guid":{"rendered":"http:\/\/www.vesuvioweb.com\/it\/?p=468"},"modified":"2012-02-09T22:19:40","modified_gmt":"2012-02-09T22:19:40","slug":"giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano","status":"publish","type":"post","link":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/","title":{"rendered":"Giuseppe Maggi &#8211; Archeologia vesuviana e territorio vesuviano"},"content":{"rendered":"<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Giuseppe-Maggi-VESUVIO_E_TERRITORIO-vesuvioweb-2012.pdf\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-470\" title=\"icona maggi ercolano 1\" src=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/Giuseppe-Maggi-VESUVIO_E_TERRITORIO-vesuvioweb-2012.pdf\">Giuseppe Maggi-VESUVIO_E_TERRITORIO-vesuvioweb 2012<\/a><\/p>\n<p>Su quest\u2019argomento esiste una specie di spartiacque: la citt\u00e0\u00a0prima e dopo la venuta di Silla in Campania durante la guerra\u00a0sociale (91-89 a.C.). La guerra fu definita \u201csociale\u201d perch\u00e9 riguard\u00f2 l\u2019ultima ribellione dei socii, cio\u00e8 degli alleati italici, contro\u00a0Roma. Il motivo fu la delusione per il mancato ottenimento della\u00a0cittadinanza e dei relativi diritti. Nacque uno Stato federale con\u00a0capitale Corfinio, ribattezzata Italica, presso Sulmona. Fu una\u00a0guerra sanguinosa, che cost\u00f2 circa trecentomila morti. Quasi\u00a0tutte le citt\u00e0 campane, con la clamorosa esclusione di Nocera,\u00a0si schierarono contro Roma.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Giuseppe Maggi-VESUVIO_E_TERRITORIO-vesuvioweb 2012 Su quest\u2019argomento esiste una specie di spartiacque:&hellip;<\/p>\n","protected":false},"author":2,"featured_media":470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[9,153],"tags":[],"class_list":["post-468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-00-in-rilievo","category-archeologia-ercolano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Giuseppe Maggi-VESUVIO_E_TERRITORIO-vesuvioweb 2012 Su quest\u2019argomento esiste una specie di spartiacque:&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/\" \/>\n<meta property=\"og:site_name\" content=\"Vesuvioweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-06T18:24:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-02-09T22:19:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"449\" \/>\n\t<meta property=\"og:image:height\" content=\"633\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vesuvioweb\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vesuvioweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/\"},\"author\":{\"name\":\"Vesuvioweb\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\"},\"headline\":\"Giuseppe Maggi &#8211; Archeologia vesuviana e territorio vesuviano\",\"datePublished\":\"2012-01-06T18:24:56+00:00\",\"dateModified\":\"2012-02-09T22:19:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-maggi-ercolano-1.jpg\",\"articleSection\":[\"00 In Rilievo\",\"Archeologia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/\",\"name\":\"Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-maggi-ercolano-1.jpg\",\"datePublished\":\"2012-01-06T18:24:56+00:00\",\"dateModified\":\"2012-02-09T22:19:40+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/01\\\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-maggi-ercolano-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-maggi-ercolano-1.jpg\",\"width\":449,\"height\":633},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"name\":\"Vesuvioweb\",\"description\":\"Magazine di Cultura Vesuviana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\",\"name\":\"Vesuvioweb\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"width\":1000,\"height\":216,\"caption\":\"Vesuvioweb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\",\"name\":\"Vesuvioweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"caption\":\"Vesuvioweb\"},\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/author\\\/vesuvioweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/","og_locale":"it_IT","og_type":"article","og_title":"Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb","og_description":"&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Giuseppe Maggi-VESUVIO_E_TERRITORIO-vesuvioweb 2012 Su quest\u2019argomento esiste una specie di spartiacque:&hellip;","og_url":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/","og_site_name":"Vesuvioweb","article_published_time":"2012-01-06T18:24:56+00:00","article_modified_time":"2012-02-09T22:19:40+00:00","og_image":[{"width":449,"height":633,"url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg","type":"image\/jpeg"}],"author":"Vesuvioweb","twitter_misc":{"Scritto da":"Vesuvioweb","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#article","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/"},"author":{"name":"Vesuvioweb","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64"},"headline":"Giuseppe Maggi &#8211; Archeologia vesuviana e territorio vesuviano","datePublished":"2012-01-06T18:24:56+00:00","dateModified":"2012-02-09T22:19:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg","articleSection":["00 In Rilievo","Archeologia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/","url":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/","name":"Giuseppe Maggi - Archeologia vesuviana e territorio vesuviano - Vesuvioweb","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#primaryimage"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg","datePublished":"2012-01-06T18:24:56+00:00","dateModified":"2012-02-09T22:19:40+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/01\/giuseppe-maggi-archeologia-vesuviana-e-territorio-vesuviano\/#primaryimage","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-maggi-ercolano-1.jpg","width":449,"height":633},{"@type":"WebSite","@id":"https:\/\/www.vesuvioweb.com\/it\/#website","url":"https:\/\/www.vesuvioweb.com\/it\/","name":"Vesuvioweb","description":"Magazine di Cultura Vesuviana","publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vesuvioweb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vesuvioweb.com\/it\/#organization","name":"Vesuvioweb","url":"https:\/\/www.vesuvioweb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","width":1000,"height":216,"caption":"Vesuvioweb"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64","name":"Vesuvioweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","caption":"Vesuvioweb"},"url":"https:\/\/www.vesuvioweb.com\/it\/author\/vesuvioweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":0,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media\/470"}],"wp:attachment":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media?parent=468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/categories?post=468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/tags?post=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}