{"id":7649,"date":"2012-04-01T16:06:52","date_gmt":"2012-04-01T15:06:52","guid":{"rendered":"http:\/\/www.vesuvioweb.com\/it\/?p=7649"},"modified":"2012-10-20T21:57:09","modified_gmt":"2012-10-20T20:57:09","slug":"carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia","status":"publish","type":"post","link":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/","title":{"rendered":"33 &#8211; Carlo Iandolo &#8211; Pillole Linguistiche Napoletane: la metafonia."},"content":{"rendered":"<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/33-Carlo-Iandolo-Pillole-Linguistiche-Napoletane-Metafonia-vesuvioweb.pdf\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-7651\" title=\"icona metafonia\" src=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia.jpg\" alt=\"\" width=\"756\" height=\"76\" srcset=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia.jpg 756w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia-300x30.jpg 300w\" sizes=\"(max-width: 756px) 100vw, 756px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/33-Carlo-Iandolo-Pillole-Linguistiche-Napoletane-Metafonia-vesuvioweb.pdf\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-7652\" title=\"icona metafonia1\" src=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia1.jpg\" alt=\"\" width=\"329\" height=\"381\" srcset=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia1.jpg 329w, https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia1-259x300.jpg 259w\" sizes=\"(max-width: 329px) 100vw, 329px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #666699;\"><strong><a href=\"http:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/33-Carlo-Iandolo-Pillole-Linguistiche-Napoletane-Metafonia-vesuvioweb.pdf\"><span style=\"color: #666699;\">33 Carlo Iandolo &#8211; Pillole Linguistiche Napoletane &#8211; Metafonia &#8211; vesuvioweb<\/span><\/a><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>33 Carlo Iandolo &#8211; Pillole Linguistiche Napoletane &#8211; Metafonia &#8211; vesuvioweb<\/p>\n","protected":false},"author":2,"featured_media":7653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[9,235],"tags":[],"class_list":["post-7649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-00-in-rilievo","category-pillole-linguistiche-napoletane"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb\" \/>\n<meta property=\"og:description\" content=\"33 Carlo Iandolo &#8211; Pillole Linguistiche Napoletane &#8211; Metafonia &#8211; vesuvioweb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Vesuvioweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-01T15:06:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-10-20T20:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"302\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vesuvioweb\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vesuvioweb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/\"},\"author\":{\"name\":\"Vesuvioweb\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\"},\"headline\":\"33 &#8211; Carlo Iandolo &#8211; Pillole Linguistiche Napoletane: la metafonia.\",\"datePublished\":\"2012-04-01T15:06:52+00:00\",\"dateModified\":\"2012-10-20T20:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/\"},\"wordCount\":19,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-metafonia2.jpg\",\"articleSection\":[\"00 In Rilievo\",\"Pillole linguistiche napoletane\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/\",\"name\":\"33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-metafonia2.jpg\",\"datePublished\":\"2012-04-01T15:06:52+00:00\",\"dateModified\":\"2012-10-20T20:57:09+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/2012\\\/04\\\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-metafonia2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/icona-metafonia2.jpg\",\"width\":302,\"height\":421},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"name\":\"Vesuvioweb\",\"description\":\"Magazine di Cultura Vesuviana\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#organization\",\"name\":\"Vesuvioweb\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/wp-content\\\/uploads\\\/vesuvioweb-logo.png\",\"width\":1000,\"height\":216,\"caption\":\"Vesuvioweb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/#\\\/schema\\\/person\\\/28ebd1937f5473de7461936741026f64\",\"name\":\"Vesuvioweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g\",\"caption\":\"Vesuvioweb\"},\"url\":\"https:\\\/\\\/www.vesuvioweb.com\\\/it\\\/author\\\/vesuvioweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/","og_locale":"it_IT","og_type":"article","og_title":"33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb","og_description":"33 Carlo Iandolo &#8211; Pillole Linguistiche Napoletane &#8211; Metafonia &#8211; vesuvioweb","og_url":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/","og_site_name":"Vesuvioweb","article_published_time":"2012-04-01T15:06:52+00:00","article_modified_time":"2012-10-20T20:57:09+00:00","og_image":[{"width":302,"height":421,"url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg","type":"image\/jpeg"}],"author":"Vesuvioweb","twitter_misc":{"Scritto da":"Vesuvioweb"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#article","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/"},"author":{"name":"Vesuvioweb","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64"},"headline":"33 &#8211; Carlo Iandolo &#8211; Pillole Linguistiche Napoletane: la metafonia.","datePublished":"2012-04-01T15:06:52+00:00","dateModified":"2012-10-20T20:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/"},"wordCount":19,"commentCount":0,"publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg","articleSection":["00 In Rilievo","Pillole linguistiche napoletane"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/","url":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/","name":"33 - Carlo Iandolo - Pillole Linguistiche Napoletane: la metafonia. - Vesuvioweb","isPartOf":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#primaryimage"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg","datePublished":"2012-04-01T15:06:52+00:00","dateModified":"2012-10-20T20:57:09+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/2012\/04\/carlo-iandolo-pillole-linguistiche-napoletane-la-metafonia\/#primaryimage","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/icona-metafonia2.jpg","width":302,"height":421},{"@type":"WebSite","@id":"https:\/\/www.vesuvioweb.com\/it\/#website","url":"https:\/\/www.vesuvioweb.com\/it\/","name":"Vesuvioweb","description":"Magazine di Cultura Vesuviana","publisher":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vesuvioweb.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vesuvioweb.com\/it\/#organization","name":"Vesuvioweb","url":"https:\/\/www.vesuvioweb.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","contentUrl":"https:\/\/www.vesuvioweb.com\/it\/wp-content\/uploads\/vesuvioweb-logo.png","width":1000,"height":216,"caption":"Vesuvioweb"},"image":{"@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vesuvioweb.com\/it\/#\/schema\/person\/28ebd1937f5473de7461936741026f64","name":"Vesuvioweb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61f8bbbe1ad3b3e83ab86f27d3858dd232cb18c4dcc23c12facd8763bf3f53b6?s=96&d=mm&r=g","caption":"Vesuvioweb"},"url":"https:\/\/www.vesuvioweb.com\/it\/author\/vesuvioweb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/7649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/comments?post=7649"}],"version-history":[{"count":0,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/posts\/7649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media\/7653"}],"wp:attachment":[{"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/media?parent=7649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/categories?post=7649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vesuvioweb.com\/it\/wp-json\/wp\/v2\/tags?post=7649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}